{"id":430,"date":"2017-01-11T17:47:05","date_gmt":"2017-01-11T16:47:05","guid":{"rendered":"https:\/\/tischlerei-penzel.de\/?p=430"},"modified":"2026-03-16T09:25:11","modified_gmt":"2026-03-16T08:25:11","slug":"ms-bremen-drydock2016","status":"publish","type":"post","link":"https:\/\/tischlerei-penzel.de\/en\/ms-bremen-drydock2016\/","title":{"rendered":"MS Bremen Drydock 2016"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":436,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,4],"tags":[],"class_list":["post-430","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-marine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MS Bremen Drydock 2016 - Tischlerei Penzel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tischlerei-penzel.de\/ms-bremen-drydock2016\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MS Bremen Drydock 2016 - Tischlerei Penzel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tischlerei-penzel.de\/ms-bremen-drydock2016\/\" \/>\n<meta property=\"og:site_name\" content=\"Tischlerei Penzel\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-11T16:47:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-16T08:25:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tischlerei-penzel.de\/wp-content\/uploads\/2017\/01\/IMG_9729.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"3264\" \/>\n\t<meta property=\"og:image:height\" content=\"2448\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"seven-penzel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"seven-penzel\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tischlerei-penzel.de\/ms-bremen-drydock2016\/\",\"url\":\"https:\/\/tischlerei-penzel.de\/ms-bremen-drydock2016\/\",\"name\":\"MS Bremen Drydock 2016 - Tischlerei Penzel\",\"isPartOf\":{\"@id\":\"https:\/\/tischlerei-penzel.de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/tischlerei-penzel.de\/ms-bremen-drydock2016\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/tischlerei-penzel.de\/ms-bremen-drydock2016\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tischlerei-penzel.de\/wp-content\/uploads\/2017\/01\/IMG_9729.jpg\",\"datePublished\":\"2017-01-11T16:47:05+00:00\",\"dateModified\":\"2026-03-16T08:25:11+00:00\",\"author\":{\"@id\":\"https:\/\/tischlerei-penzel.de\/#\/schema\/person\/654ede1f0c872c83d96dc52903e35461\"},\"breadcrumb\":{\"@id\":\"https:\/\/tischlerei-penzel.de\/ms-bremen-drydock2016\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tischlerei-penzel.de\/ms-bremen-drydock2016\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/tischlerei-penzel.de\/ms-bremen-drydock2016\/#primaryimage\",\"url\":\"https:\/\/tischlerei-penzel.de\/wp-content\/uploads\/2017\/01\/IMG_9729.jpg\",\"contentUrl\":\"https:\/\/tischlerei-penzel.de\/wp-content\/uploads\/2017\/01\/IMG_9729.jpg\",\"width\":3264,\"height\":2448},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tischlerei-penzel.de\/ms-bremen-drydock2016\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/tischlerei-penzel.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MS Bremen Drydock 2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tischlerei-penzel.de\/#website\",\"url\":\"https:\/\/tischlerei-penzel.de\/\",\"name\":\"Tischlerei Penzel\",\"description\":\"Modernes Holzhandwerk\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tischlerei-penzel.de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/tischlerei-penzel.de\/#\/schema\/person\/654ede1f0c872c83d96dc52903e35461\",\"name\":\"seven-penzel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/tischlerei-penzel.de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/67cd04cdeef1a66b0cb44be33a3f805478582cde2dd2d3cb0714b9dc88c69c68?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/67cd04cdeef1a66b0cb44be33a3f805478582cde2dd2d3cb0714b9dc88c69c68?s=96&d=mm&r=g\",\"caption\":\"seven-penzel\"},\"url\":\"https:\/\/tischlerei-penzel.de\/en\/author\/seven-penzel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MS Bremen Drydock 2016 - Tischlerei Penzel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tischlerei-penzel.de\/ms-bremen-drydock2016\/","og_locale":"en_US","og_type":"article","og_title":"MS Bremen Drydock 2016 - Tischlerei Penzel","og_url":"https:\/\/tischlerei-penzel.de\/ms-bremen-drydock2016\/","og_site_name":"Tischlerei Penzel","article_published_time":"2017-01-11T16:47:05+00:00","article_modified_time":"2026-03-16T08:25:11+00:00","og_image":[{"width":3264,"height":2448,"url":"https:\/\/tischlerei-penzel.de\/wp-content\/uploads\/2017\/01\/IMG_9729.jpg","type":"image\/jpeg"}],"author":"seven-penzel","twitter_card":"summary_large_image","twitter_misc":{"Written by":"seven-penzel"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tischlerei-penzel.de\/ms-bremen-drydock2016\/","url":"https:\/\/tischlerei-penzel.de\/ms-bremen-drydock2016\/","name":"MS Bremen Drydock 2016 - Tischlerei Penzel","isPartOf":{"@id":"https:\/\/tischlerei-penzel.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tischlerei-penzel.de\/ms-bremen-drydock2016\/#primaryimage"},"image":{"@id":"https:\/\/tischlerei-penzel.de\/ms-bremen-drydock2016\/#primaryimage"},"thumbnailUrl":"https:\/\/tischlerei-penzel.de\/wp-content\/uploads\/2017\/01\/IMG_9729.jpg","datePublished":"2017-01-11T16:47:05+00:00","dateModified":"2026-03-16T08:25:11+00:00","author":{"@id":"https:\/\/tischlerei-penzel.de\/#\/schema\/person\/654ede1f0c872c83d96dc52903e35461"},"breadcrumb":{"@id":"https:\/\/tischlerei-penzel.de\/ms-bremen-drydock2016\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tischlerei-penzel.de\/ms-bremen-drydock2016\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/tischlerei-penzel.de\/ms-bremen-drydock2016\/#primaryimage","url":"https:\/\/tischlerei-penzel.de\/wp-content\/uploads\/2017\/01\/IMG_9729.jpg","contentUrl":"https:\/\/tischlerei-penzel.de\/wp-content\/uploads\/2017\/01\/IMG_9729.jpg","width":3264,"height":2448},{"@type":"BreadcrumbList","@id":"https:\/\/tischlerei-penzel.de\/ms-bremen-drydock2016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/tischlerei-penzel.de\/"},{"@type":"ListItem","position":2,"name":"MS Bremen Drydock 2016"}]},{"@type":"WebSite","@id":"https:\/\/tischlerei-penzel.de\/#website","url":"https:\/\/tischlerei-penzel.de\/","name":"Tischlerei Penzel","description":"Modernes Holzhandwerk","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tischlerei-penzel.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/tischlerei-penzel.de\/#\/schema\/person\/654ede1f0c872c83d96dc52903e35461","name":"seven-penzel","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/tischlerei-penzel.de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/67cd04cdeef1a66b0cb44be33a3f805478582cde2dd2d3cb0714b9dc88c69c68?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/67cd04cdeef1a66b0cb44be33a3f805478582cde2dd2d3cb0714b9dc88c69c68?s=96&d=mm&r=g","caption":"seven-penzel"},"url":"https:\/\/tischlerei-penzel.de\/en\/author\/seven-penzel\/"}]}},"_links":{"self":[{"href":"https:\/\/tischlerei-penzel.de\/en\/wp-json\/wp\/v2\/posts\/430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tischlerei-penzel.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tischlerei-penzel.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tischlerei-penzel.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tischlerei-penzel.de\/en\/wp-json\/wp\/v2\/comments?post=430"}],"version-history":[{"count":4,"href":"https:\/\/tischlerei-penzel.de\/en\/wp-json\/wp\/v2\/posts\/430\/revisions"}],"predecessor-version":[{"id":709,"href":"https:\/\/tischlerei-penzel.de\/en\/wp-json\/wp\/v2\/posts\/430\/revisions\/709"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tischlerei-penzel.de\/en\/wp-json\/wp\/v2\/media\/436"}],"wp:attachment":[{"href":"https:\/\/tischlerei-penzel.de\/en\/wp-json\/wp\/v2\/media?parent=430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tischlerei-penzel.de\/en\/wp-json\/wp\/v2\/categories?post=430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tischlerei-penzel.de\/en\/wp-json\/wp\/v2\/tags?post=430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}